{"id":26516,"date":"2026-02-10T10:04:49","date_gmt":"2026-02-10T14:04:49","guid":{"rendered":"https:\/\/mmcereais.com.br\/2026\/soja\/tecnica-com-bacterias-aumenta-produtividade-da-soja-em-mais-de-8-no-parana\/"},"modified":"2026-02-10T10:04:49","modified_gmt":"2026-02-10T14:04:49","slug":"tecnica-com-bacterias-aumenta-produtividade-da-soja-em-mais-de-8-no-parana","status":"publish","type":"post","link":"https:\/\/mmcereais.com.br\/en\/2026\/soja\/tecnica-com-bacterias-aumenta-produtividade-da-soja-em-mais-de-8-no-parana\/","title":{"rendered":"T\u00e9cnica com bact\u00e9rias aumenta produtividade da soja em mais de 8% no Paran\u00e1"},"content":{"rendered":"<p><\/p>\n<div id=\"mvp-content-main\" class=\"left relative\">\n<p>Desde a safra 2015\/2016, a\u00a0Embrapa Soja\u00a0(PR) e o Instituto de Desenvolvimento Rural do Paran\u00e1 (IDR-Paran\u00e1) acompanham e validam a ado\u00e7\u00e3o de boas pr\u00e1ticas de fixa\u00e7\u00e3o biol\u00f3gica de nitrog\u00eanio (<a href=\"https:\/\/www.embrapa.br\/tema-fixacao-biologica-de-nitrogenio\" target=\"_blank\" rel=\"noopener\">FBN<\/a>\u00a0\u2013 leia sobre o tema no quadro abaixo da mat\u00e9ria) entre produtores do estado, com registro de aumento m\u00e9dio de 8,33% na produtividade a partir da coinocula\u00e7\u00e3o de sementes. A coinocula\u00e7\u00e3o consiste na aplica\u00e7\u00e3o conjunta de dois ou mais microrganismos ben\u00e9ficos, potencializando a a\u00e7\u00e3o da FBN e aliando rentabilidade \u00e0 sustentabilidade econ\u00f4mica e ambiental.<\/p>\n<p>Os dados obtidos ao longo da \u00faltima d\u00e9cada est\u00e3o dispon\u00edveis na publica\u00e7\u00e3o\u00a0Coinocula\u00e7\u00e3o da soja com Bradyrhizobium e Azospirillum na safra 2024\/2025 no Paran\u00e1, que apresenta os resultados em lavouras paranaenses, em Unidades de Refer\u00eancia Tecnol\u00f3gica\u00a0 (URTs). S\u00e3o autores da publica\u00e7\u00e3o\u00a0Andr\u00e9 Mateus Prando,\u00a0Arnold Barbosa de Oliveira,\u00a0Divania de Lima,\u00a0Edison Ulisses Ramos J\u00fanior, Edivan Jos\u00e9 Possamai, Eliana Aparecida Reis,\u00a0Marco Antonio Nogueira\u00a0e\u00a0Mariangela Hungria.<\/p>\n<p><a href=\"https:\/\/www.embrapa.br\/documents\/10180\/106428292\/260210_Benefi%CC%81ciosBioinsumosSoja_Antonio_Neto_horizontal.jpg\/2e433834-0a5a-c280-a74a-9d3669bf8f1b?t=1770500153651\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/www.embrapa.br\/documents\/10180\/106428292\/260210_Benefi%CC%81ciosBioinsumosSoja_Antonio_Neto_horizontal.jpg\/2e433834-0a5a-c280-a74a-9d3669bf8f1b?t=1770500153651\" alt width=\"339\" height=\"226\"><\/a>\u201cNesses dez anos, as URTs, que s\u00e3o conduzidas diretamente em lavouras comerciais em propriedades rurais, permitiram avaliar e validar a efetividade da tecnologia na pr\u00e1tica. Os resultados obtidos ano ap\u00f3s ano confirmaram que o uso adequado da inocula\u00e7\u00e3o\/coinocula\u00e7\u00e3o aumentou a produtividade da soja e isentou os agricultores de custos com a aduba\u00e7\u00e3o nitrogenada na cultura, garantindo aumento da rentabilidade e benef\u00edcios ambientais para toda a sociedade\u201d, afirmam o pesquisador Andr\u00e9 Prando, da Embrapa Soja, e Edivan Possamai, coordenador t\u00e9cnico do projeto Gr\u00e3os do IDR-Paran\u00e1.<\/p>\n<p>A exist\u00eancia de uma rede de URTs em todo o Paran\u00e1, estruturada pelo IDR-Paran\u00e1 com o apoio da Embrapa, possibilitou a inser\u00e7\u00e3o da inocula\u00e7\u00e3o com as bact\u00e9rias\u00a0Bradyrhizobium\u00a0no protocolo de valida\u00e7\u00e3o de tecnologias na safra 2015\/2016. A coinocula\u00e7\u00e3o passou a ser validada a partir da safra 2017\/2018, com o avan\u00e7o das pesquisas e as constata\u00e7\u00f5es de que o Azospirillum, bact\u00e9ria promotora de crescimento em plantas, era um aliado do Bradyrhizobium no aumento da produtividade de gr\u00e3os de soja.<\/p>\n<p>De acordo com Possamai, foram obtidos dados em 22 URTs, instaladas em lavouras comerciais de 17 munic\u00edpios, de diferentes regi\u00f5es do Paran\u00e1, na safra 2024\/2025. \u201cEssas URTs, pela sua diversidade geogr\u00e1fica, s\u00e3o importantes referenciais para a tecnologia de inocula\u00e7\u00e3o e coinocula\u00e7\u00e3o. Elas oferecem um panorama do que ocorreu na safra, uma vez que os locais apresentam diferentes tipos de solo, clima, sistemas de cultivo, sucess\u00e3o a diversas culturas (milho segunda safra, trigo, aveia, azev\u00e9m, etc.), \u00e9pocas de semeadura (antecipada, normal ou tardia) e n\u00edveis de tecnologias empregadas pelos produtores\u201d, analisa Possamai.<\/p>\n<p><a href=\"https:\/\/www.embrapa.br\/documents\/10180\/106428292\/260210_Benefi%CC%81ciosBioinsumosSoja_Antonio_Neto_horizontal2.jpg\/481e1fab-5bba-47c5-15c4-786aa15fdc3c?t=1770500307426\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"alignright\" src=\"https:\/\/www.embrapa.br\/documents\/10180\/106428292\/260210_Benefi%CC%81ciosBioinsumosSoja_Antonio_Neto_horizontal2.jpg\/481e1fab-5bba-47c5-15c4-786aa15fdc3c?t=1770500307426\" alt width=\"298\" height=\"198\"><\/a>Segundo levantamento do IDR-Paran\u00e1 e da Embrapa Soja, a produtividade m\u00e9dia de gr\u00e3os nas \u00e1reas coinoculadas foi de 3.916 quilogramas por hectare (kg\/ha), enquanto nas \u00e1reas n\u00e3o inoculadas, foi de 3.615 kg\/ha. A produtividade m\u00e9dia nas URTs com a coinocula\u00e7\u00e3o na safra 2024\/2025 foi superior \u00e0 m\u00e9dia paranaense de 3.663 kg\/ha e \u00e0 m\u00e9dia nacional de 3.561 kg\/ha, conforme a Companhia Nacional de Abastecimento (Conab).<\/p>\n<p>Na m\u00e9dia estadual, 64% dos produtores paranaenses consultados afirmaram ter utilizado inoculante no cultivo da soja na safra 2024\/2025. A m\u00e9dia de uso da coinocula\u00e7\u00e3o com Bradyrhizobium e Azospirillum foi de 28% na safra 2024\/2025, de acordo com a Associa\u00e7\u00e3o Nacional de Promo\u00e7\u00e3o e Inova\u00e7\u00e3o da Ind\u00fastria de Biol\u00f3gicos (ANPII Bio), em pesquisa de mercado realizada pela\u00a0Kynetec, no Paran\u00e1.<\/p>\n<h4><strong>Benef\u00edcios da tecnologia<\/strong><\/h4>\n<p>Pesquisas conduzidas pelos pesquisadores da Embrapa Soja Mariangela Hungria e Marco Antonio Nogueira revelam que a inocula\u00e7\u00e3o anual da soja com a bact\u00e9ria\u00a0Bradyrhizobium, mesmo em \u00e1reas tradicionais de cultivo que j\u00e1 receberam inoculantes anteriormente, garantem tetos de produtividade sem nenhuma aplica\u00e7\u00e3o de fertilizante nitrogenado.<\/p>\n<p>Al\u00e9m da inocula\u00e7\u00e3o anual com\u00a0Bradyrhizobium, a partir da safra 2013\/2014 a Embrapa passou a indicar o uso conjunto de uma segunda bact\u00e9ria para a inocula\u00e7\u00e3o da soja no processo denominado coinocula\u00e7\u00e3o, que conta com duas estirpes da esp\u00e9cie Azospirillum brasilense (Ab-V5 e Ab-V6). \u201cAs plantas de soja coinoculadas com Bradyrhizobium e Azospirillum apresentam nodula\u00e7\u00e3o mais abundante e precoce, aumentando os ganhos proporcionados pela inocula\u00e7\u00e3o anual apenas com Bradyrhizobium\u201d, destaca Hungria.<\/p>\n<\/div>\n<h6><em>THE <strong>MM Cereais<\/strong> works with the best grains on the market and also keeps you up to date with the latest news and analyses on agribusiness.<br \/>\nDon&#039;t forget to follow our social networks.<\/em><\/h6>\n<p><a href=\"https:\/\/opresenterural.com.br\/tecnica-com-bacterias-aumenta-produtividade-da-soja-em-mais-de-8-no-parana\/\" target=\"_blank\" rel=\"noopener\">Access News Source <\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Desde a safra 2015\/2016, a\u00a0Embrapa Soja\u00a0(PR) e o Instituto de Desenvolvimento Rural do Paran\u00e1 (IDR-Paran\u00e1)&hellip;<\/p>","protected":false},"author":1,"featured_media":26517,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[259],"tags":[],"class_list":["post-26516","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-soja"],"_links":{"self":[{"href":"https:\/\/mmcereais.com.br\/en\/wp-json\/wp\/v2\/posts\/26516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mmcereais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mmcereais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mmcereais.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mmcereais.com.br\/en\/wp-json\/wp\/v2\/comments?post=26516"}],"version-history":[{"count":0,"href":"https:\/\/mmcereais.com.br\/en\/wp-json\/wp\/v2\/posts\/26516\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mmcereais.com.br\/en\/wp-json\/wp\/v2\/media\/26517"}],"wp:attachment":[{"href":"https:\/\/mmcereais.com.br\/en\/wp-json\/wp\/v2\/media?parent=26516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mmcereais.com.br\/en\/wp-json\/wp\/v2\/categories?post=26516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mmcereais.com.br\/en\/wp-json\/wp\/v2\/tags?post=26516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}